{"id":646,"date":"2016-02-07T19:38:30","date_gmt":"2016-02-07T17:38:30","guid":{"rendered":"https:\/\/www.tigermoonrecords.de\/de\/?p=646"},"modified":"2016-02-07T19:38:30","modified_gmt":"2016-02-07T17:38:30","slug":"shoot-the-moon-big-black-dogs","status":"publish","type":"post","link":"https:\/\/www.tigermoonrecords.de\/de\/shoot-the-moon-big-black-dogs\/","title":{"rendered":"Shoot the Moon &#8211; Big Black Dogs"},"content":{"rendered":"<h1><\/h1>\n<p>New Vocal Jazz<\/p>\n<p><a href=\"http:\/\/www.shootthemoonberlin.de\/wp-content\/uploads\/2011\/10\/FJ_0611klein.jpg\" rel=\"lightbox[7]\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-391\" title=\"\" src=\"http:\/\/www.shootthemoonberlin.de\/wp-content\/uploads\/2011\/10\/FJ_0611klein-283x300.jpg\" alt=\"\" width=\"283\" height=\"300\" \/><\/a><br \/>\nAlmut Schlichting \u2013 Saxofon, Komposition<br \/>\nWinnie Br\u00fcckner \u2013 Gesang<br \/>\nTobias Dettbarn \u2013 Bassklarinette<br \/>\nSven Hinse \u2013 Kontrabass<br \/>\nPhilipp Bernhardt \u2013 Schlagzeug<\/p>\n<p>Das Berliner Quintett Shoot the Moon entwickelt aus den farbenfrohen Songs der Bandleaderin Almut Schlichting ein dichtes Netz an Erz\u00e4hlebenen, in dem die Zuh\u00f6rer ihrer eigenen Fantasie freien Lauf lassen k\u00f6nnen.<\/p>\n<p>Im neuen Programm \u201eBig Black Dogs\u201c verbinden Shoot the Moon zeitgen\u00f6ssischen Jazz, Retro-Pop und imagin\u00e4ren Folk zu einem Soundtrack f\u00fcr Sp\u00e4tsommersonntage. Sie surfen durch die urbane Flora und Fauna und schaffen \u2013 wie musikalische Guerilla-G\u00e4rtner \u2013 unerwartete Idyllen in der Stadtlandschaft.<br \/>\nInspiriert von Alltagsgeschichten und Streifz\u00fcgen durch die englischen Buchl\u00e4den der Stadt bev\u00f6lkern skurrile, m\u00e4rchenhafte, heitere und d\u00fcstere Gestalten Almut Schlichtings Kompositionen: New Yorker High Society Ladies, g\u00e4lische Hexen, manische Kaffeetrinker, M\u00f6chtegerncowboys, Kobolde, K\u00f6niginnen im Ruhestand, Schnecken, zauberkr\u00e4ftige Fische \u2013 und nicht zuletzt gro\u00dfe schwarze Hunde.<br \/>\nLebendig werden die Songs durch die traumwandlerisch eingespielte Band; durch den virtuosen Charme der Gesangsparts, die warmen Sounds der Bassklarinette und des Altsaxofons, die durchl\u00e4ssig groovende Rhythmusgruppe und die fantasievollen Improvisationspassagen.<br \/>\nShoot the Moon waren 2005 Preistr\u00e4ger des Studiowettbewerbs des Berliner Senats und haben drei von der Presse hochgelobte CDs ver\u00f6ffentlicht (\u201eTreasure Island\u201c nrw records 2006, \u201eGlory &amp; Decay\u201c jazzwerkstatt 2009). Seitdem haben sie sich in zahlreichen Club- und Festivalkonzerten in die Herzen des Publikums gespielt. Auch die neueste CD \u201eBig Black Dogs\u201c (Wismart \/ NRW Vertrieb 2013) hat bei der Presse und in Konzerten gro\u00dfen Anklang gefunden.<\/p>\n<p><a href=\"http:\/\/www.shootthemoonberlin.de\/\" target=\"_blank\">www.shootthemoonberlin.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>New Vocal Jazz Almut Schlichting \u2013 Saxofon, Komposition Winnie Br\u00fcckner \u2013 Gesang Tobias Dettbarn \u2013 Bassklarinette Sven Hinse \u2013 Kontrabass Philipp Bernhardt \u2013 Schlagzeug Das Berliner Quintett Shoot the Moon entwickelt aus den farbenfrohen Songs der Bandleaderin Almut Schlichting ein dichtes Netz an Erz\u00e4hlebenen, in dem die Zuh\u00f6rer ihrer eigenen Fantasie freien Lauf lassen k\u00f6nnen&#8230;.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-646","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.tigermoonrecords.de\/de\/wp-json\/wp\/v2\/posts\/646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tigermoonrecords.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tigermoonrecords.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tigermoonrecords.de\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tigermoonrecords.de\/de\/wp-json\/wp\/v2\/comments?post=646"}],"version-history":[{"count":1,"href":"https:\/\/www.tigermoonrecords.de\/de\/wp-json\/wp\/v2\/posts\/646\/revisions"}],"predecessor-version":[{"id":647,"href":"https:\/\/www.tigermoonrecords.de\/de\/wp-json\/wp\/v2\/posts\/646\/revisions\/647"}],"wp:attachment":[{"href":"https:\/\/www.tigermoonrecords.de\/de\/wp-json\/wp\/v2\/media?parent=646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tigermoonrecords.de\/de\/wp-json\/wp\/v2\/categories?post=646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tigermoonrecords.de\/de\/wp-json\/wp\/v2\/tags?post=646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}